{"id":161,"count":1,"description":"","link":"https:\/\/www.ipresas.com\/localizacion-proyectos\/guatemala\/","name":"Guatemala","slug":"guatemala","taxonomy":"localizacion_proyectos","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guatemala - iPresas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ipresas.com\/localizacion-proyectos\/guatemala\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guatemala - iPresas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ipresas.com\/localizacion-proyectos\/guatemala\/\" \/>\n<meta property=\"og:site_name\" content=\"iPresas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ipresas.com\\\/localizacion-proyectos\\\/guatemala\\\/\",\"url\":\"https:\\\/\\\/www.ipresas.com\\\/localizacion-proyectos\\\/guatemala\\\/\",\"name\":\"Guatemala - iPresas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipresas.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ipresas.com\\\/localizacion-proyectos\\\/guatemala\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ipresas.com\\\/localizacion-proyectos\\\/guatemala\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ipresas.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guatemala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ipresas.com\\\/#website\",\"url\":\"https:\\\/\\\/www.ipresas.com\\\/\",\"name\":\"iPresas\",\"description\":\"An\u00e1lisis de Riesgos en seguridad de presas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipresas.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ipresas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ipresas.com\\\/#organization\",\"name\":\"iPresas\",\"url\":\"https:\\\/\\\/www.ipresas.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ipresas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ipresas.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.ipresas.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-logo.png\",\"width\":263,\"height\":129,\"caption\":\"iPresas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipresas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guatemala - iPresas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ipresas.com\/localizacion-proyectos\/guatemala\/","og_locale":"en_US","og_type":"article","og_title":"Guatemala - iPresas","og_url":"https:\/\/www.ipresas.com\/localizacion-proyectos\/guatemala\/","og_site_name":"iPresas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ipresas.com\/localizacion-proyectos\/guatemala\/","url":"https:\/\/www.ipresas.com\/localizacion-proyectos\/guatemala\/","name":"Guatemala - iPresas","isPartOf":{"@id":"https:\/\/www.ipresas.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.ipresas.com\/localizacion-proyectos\/guatemala\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ipresas.com\/localizacion-proyectos\/guatemala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ipresas.com\/en\/"},{"@type":"ListItem","position":2,"name":"Guatemala"}]},{"@type":"WebSite","@id":"https:\/\/www.ipresas.com\/#website","url":"https:\/\/www.ipresas.com\/","name":"iPresas","description":"An\u00e1lisis de Riesgos en seguridad de presas","publisher":{"@id":"https:\/\/www.ipresas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ipresas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ipresas.com\/#organization","name":"iPresas","url":"https:\/\/www.ipresas.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ipresas.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.ipresas.com\/wp-content\/uploads\/2023\/04\/cropped-logo.png","contentUrl":"https:\/\/www.ipresas.com\/wp-content\/uploads\/2023\/04\/cropped-logo.png","width":263,"height":129,"caption":"iPresas"},"image":{"@id":"https:\/\/www.ipresas.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ipresas.com\/en\/wp-json\/wp\/v2\/localizacion_proyectos\/161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ipresas.com\/en\/wp-json\/wp\/v2\/localizacion_proyectos"}],"about":[{"href":"https:\/\/www.ipresas.com\/en\/wp-json\/wp\/v2\/taxonomies\/localizacion_proyectos"}],"wp:post_type":[{"href":"https:\/\/www.ipresas.com\/en\/wp-json\/wp\/v2\/proyecto?localizacion_proyectos=161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}